{"id":2848,"date":"2015-04-01T11:13:23","date_gmt":"2015-04-01T10:13:23","guid":{"rendered":"http:\/\/ludocorpus.org\/?p=2848"},"modified":"2016-02-12T12:04:44","modified_gmt":"2016-02-12T11:04:44","slug":"table-ronde-sur-les-jeux-dargent-lundi-20-avril-19h-au-centre-pompidou","status":"publish","type":"post","link":"https:\/\/2015-2018.ludocorpus.org\/en\/table-ronde-sur-les-jeux-dargent-lundi-20-avril-19h-au-centre-pompidou\/","title":{"rendered":"Table ronde &#8220;Joueurs en soci\u00e9t\u00e9&#8221;"},"content":{"rendered":"<p>Malgr\u00e9 la crise, l&#8217;industrie des jeux de hasard en France ne s&#8217;est jamais aussi bien port\u00e9e.<br \/>\nLes joueurs y voient une possibilit\u00e9 d\u2019ascension sociale que le travail ne permet plus, un moyen de se sociabiliser ou une parenth\u00e8se de libert\u00e9 dans un monde moderne qui cherche \u00e0 abolir l&#8217;irrationalit\u00e9 et le hasard.<\/p>\n<p>Programme<br \/>\nRencontre organis\u00e9e dans le cadre du cycle &#8220;Lire le Monde&#8221; et du Nouveau Festival du Centre Pompidou.<\/p>\n<p>Avec :<br \/>\nThomas Amadieu, sociologue<\/p>\n<p>Marie Redon, g\u00e9ographe<\/p>\n<p>Marc Valleur, psychiatre, responsable de l&#8217;h\u00f4pital Marmottan<\/p>\n<p>Anim\u00e9e par Marie Trespeuch, sociologue et \u00e9conomiste<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Malgr\u00e9 la crise, l&#8217;industrie des jeux de hasard en France ne s&#8217;est jamais aussi bien port\u00e9e. Les joueurs y voient une possibilit\u00e9 d\u2019ascension sociale que le travail ne permet plus, un moyen de se sociabiliser ou une parenth\u00e8se de libert\u00e9 dans un monde moderne qui cherche \u00e0 abolir l&#8217;irrationalit\u00e9 et le hasard. Programme Rencontre organis\u00e9e &hellip; <a href=\"https:\/\/2015-2018.ludocorpus.org\/en\/table-ronde-sur-les-jeux-dargent-lundi-20-avril-19h-au-centre-pompidou\/\" class=\"more-link\">Continue reading <span class=\"screen-reader-text\">Table ronde &#8220;Joueurs en soci\u00e9t\u00e9&#8221;<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[65,63],"tags":[19],"class_list":["post-2848","post","type-post","status-publish","format-standard","hentry","category-colloques-journees-detudes-tables-rondes","category-manifestations-et-evenements","tag-jeux-dargent-et-de-hasard"],"_links":{"self":[{"href":"https:\/\/2015-2018.ludocorpus.org\/en\/wp-json\/wp\/v2\/posts\/2848","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/2015-2018.ludocorpus.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/2015-2018.ludocorpus.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/2015-2018.ludocorpus.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/2015-2018.ludocorpus.org\/en\/wp-json\/wp\/v2\/comments?post=2848"}],"version-history":[{"count":0,"href":"https:\/\/2015-2018.ludocorpus.org\/en\/wp-json\/wp\/v2\/posts\/2848\/revisions"}],"wp:attachment":[{"href":"https:\/\/2015-2018.ludocorpus.org\/en\/wp-json\/wp\/v2\/media?parent=2848"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/2015-2018.ludocorpus.org\/en\/wp-json\/wp\/v2\/categories?post=2848"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/2015-2018.ludocorpus.org\/en\/wp-json\/wp\/v2\/tags?post=2848"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}